{"id":6498,"date":"2025-05-26T09:40:35","date_gmt":"2025-05-26T09:40:35","guid":{"rendered":"https:\/\/staging.superstudioevents.com\/?post_type=progetto&#038;p=6498"},"modified":"2025-06-24T14:25:22","modified_gmt":"2025-06-24T14:25:22","slug":"4-ferrari","status":"publish","type":"progetto","link":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/","title":{"rendered":"2023 Ferrari Roma Spider Presentation"},"content":{"rendered":"<p class=\"wp-block-paragraph\">New version of the iconic Ferrari Roma with an openable roof and timeless design<\/p>","protected":false},"excerpt":{"rendered":"<p>New version of the iconic Ferrari Roma with an openable roof and timeless design<\/p>","protected":false},"featured_media":6480,"menu_order":0,"template":"","pagina":[160],"class_list":["post-6498","progetto","type-progetto","status-publish","has-post-thumbnail","hentry","pagina-superstudio-piu"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presentazione 2023 Ferrari Roma Spider - Superstudio<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presentazione 2023 Ferrari Roma Spider - Superstudio\" \/>\n<meta property=\"og:description\" content=\"Nuova versione dell\u2019iconica Ferrari Roma con tetto apribile e dal design senza tempo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/\" \/>\n<meta property=\"og:site_name\" content=\"Superstudio\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-24T14:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2025\/05\/4-SSPiu-1920p.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/\",\"url\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/\",\"name\":\"Presentazione 2023 Ferrari Roma Spider - Superstudio\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/staging.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/4-SSPiu-1920p.webp\",\"datePublished\":\"2025-05-26T09:40:35+00:00\",\"dateModified\":\"2025-06-24T14:25:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/staging.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/4-SSPiu-1920p.webp\",\"contentUrl\":\"https:\\\/\\\/staging.superstudioevents.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/4-SSPiu-1920p.webp\",\"width\":1920,\"height\":1280,\"caption\":\"Ferrari - Superstudio Pi\u00f9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/progetto\\\/4-ferrari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/staging.superstudioevents.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetti\",\"item\":\"https:\\\/\\\/staging.superstudioevents.com\\\/progetto\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Presentazione 2023 Ferrari Roma Spider\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/\",\"name\":\"Superstudio\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#organization\",\"name\":\"Superstudio\",\"url\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/staging.superstudioevents.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/superstudio-logo-black-red.svg\",\"contentUrl\":\"https:\\\/\\\/staging.superstudioevents.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/superstudio-logo-black-red.svg\",\"width\":229,\"height\":44,\"caption\":\"Superstudio\"},\"image\":{\"@id\":\"https:\\\/\\\/staging.superstudioevents.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presentazione 2023 Ferrari Roma Spider - Superstudio","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"Presentazione 2023 Ferrari Roma Spider - Superstudio","og_description":"Nuova versione dell\u2019iconica Ferrari Roma con tetto apribile e dal design senza tempo","og_url":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/","og_site_name":"Superstudio","article_modified_time":"2025-06-24T14:25:22+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2025\/05\/4-SSPiu-1920p.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/","url":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/","name":"Presentazione 2023 Ferrari Roma Spider - Superstudio","isPartOf":{"@id":"https:\/\/staging.superstudioevents.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/#primaryimage"},"image":{"@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/#primaryimage"},"thumbnailUrl":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2025\/05\/4-SSPiu-1920p.webp","datePublished":"2025-05-26T09:40:35+00:00","dateModified":"2025-06-24T14:25:22+00:00","breadcrumb":{"@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/#primaryimage","url":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2025\/05\/4-SSPiu-1920p.webp","contentUrl":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2025\/05\/4-SSPiu-1920p.webp","width":1920,"height":1280,"caption":"Ferrari - Superstudio Pi\u00f9"},{"@type":"BreadcrumbList","@id":"https:\/\/staging.superstudioevents.com\/en\/progetto\/4-ferrari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/staging.superstudioevents.com\/"},{"@type":"ListItem","position":2,"name":"Progetti","item":"https:\/\/staging.superstudioevents.com\/progetto\/"},{"@type":"ListItem","position":3,"name":"Presentazione 2023 Ferrari Roma Spider"}]},{"@type":"WebSite","@id":"https:\/\/staging.superstudioevents.com\/en\/#website","url":"https:\/\/staging.superstudioevents.com\/en\/","name":"Superstudio","description":"","publisher":{"@id":"https:\/\/staging.superstudioevents.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/staging.superstudioevents.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/staging.superstudioevents.com\/en\/#organization","name":"Superstudio","url":"https:\/\/staging.superstudioevents.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/staging.superstudioevents.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2024\/11\/superstudio-logo-black-red.svg","contentUrl":"https:\/\/staging.superstudioevents.com\/wp-content\/uploads\/2024\/11\/superstudio-logo-black-red.svg","width":229,"height":44,"caption":"Superstudio"},"image":{"@id":"https:\/\/staging.superstudioevents.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/progetto\/6498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/progetto"}],"about":[{"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/types\/progetto"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/media\/6480"}],"wp:attachment":[{"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/media?parent=6498"}],"wp:term":[{"taxonomy":"pagina","embeddable":true,"href":"https:\/\/staging.superstudioevents.com\/en\/wp-json\/wp\/v2\/pagina?post=6498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}